{"id":11286,"date":"2021-09-06T10:09:10","date_gmt":"2021-09-06T08:09:10","guid":{"rendered":"https:\/\/www.hallein.com\/erleben\/veranstaltung\/die-halleiner-tschikweiber-von-1869-bis-1940-2\/"},"modified":"2021-09-06T10:09:10","modified_gmt":"2021-09-06T08:09:10","slug":"die-halleiner-tschikweiber-von-1869-bis-1940-2","status":"publish","type":"cpt_event","link":"https:\/\/www.hallein.com\/en\/erleben\/veranstaltung\/die-halleiner-tschikweiber-von-1869-bis-1940-2\/","title":{"rendered":"Die Halleiner Tschikweiber von 1869 bis 1940"},"content":{"rendered":"<p><strong>Vortrag \u00fcber die Geschichte der Halleiner Tabakfabrik und ihrer Arbeiterinnen<\/strong><\/p>\n<p>Der Vortrag behandelt die Entwicklung der Fabrik von den Anf\u00e4ngen im Jahre 1869 bis zur erzwungenen Schlie\u00dfung im Jahre 1940 und zeigt am Beispiel der Tschikweiber, wie aus einer Schar weitgehend rechtloser Arbeiterinnen durch ihre Solidarit\u00e4t eine Gemeinschaft selbstbewusster Individuen wurde. Die Darstellung dieser Fabrikgeschichte ist als Erg\u00e4nzung zur heurigen Wiederauff\u00fchrung des Erfolgsst\u00fccks \u201eTschikweiber\u201c des Theaters bodiendsole gedacht.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vortrag \u00fcber die Geschichte der Halleiner Tabakfabrik und ihrer Arbeiterinnen Der Vortrag behandelt die Entwicklung der Fabrik von den Anf\u00e4ngen im Jahre 1869 bis zur erzwungenen Schlie\u00dfung im Jahre 1940 und zeigt am Beispiel der Tschikweiber, wie aus einer Schar weitgehend rechtloser Arbeiterinnen durch ihre Solidarit\u00e4t eine Gemeinschaft selbstbewusster Individuen wurde. Die Darstellung dieser Fabrikgeschichte [&hellip;]<\/p>\n","protected":false},"featured_media":9894,"menu_order":0,"template":"","class_list":["post-11286","cpt_event","type-cpt_event","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.hallein.com\/en\/wp-json\/wp\/v2\/cpt_event\/11286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hallein.com\/en\/wp-json\/wp\/v2\/cpt_event"}],"about":[{"href":"https:\/\/www.hallein.com\/en\/wp-json\/wp\/v2\/types\/cpt_event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hallein.com\/en\/wp-json\/wp\/v2\/media\/9894"}],"wp:attachment":[{"href":"https:\/\/www.hallein.com\/en\/wp-json\/wp\/v2\/media?parent=11286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}